{"id":63348,"date":"2024-11-30T00:00:00","date_gmt":"2024-11-29T23:00:00","guid":{"rendered":"https:\/\/www.secvergnaud.com\/?post_type=weblex-importer-post&p=63348"},"modified":"2024-11-30T00:00:00","modified_gmt":"2024-11-29T23:00:00","slug":"tva-23010","status":"publish","type":"weblex-importer-post","link":"https:\/\/www.secvergnaud.com\/index.php\/les-infos-du-jour\/tva-23010\/","title":{"rendered":"TVA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Pour les redevables soumis au r\u00e9gime simplifi\u00e9 d\u2019imposition, date limite de d\u00e9p\u00f4t de la d\u00e9claration annuelle de TVA (CA 12 E) au titre de l\u2019exercice clos le 31 ao\u00fbt 2024<\/p>\n<p>Pour les entreprises redevables de la TVA d\u00e9posant leur d\u00e9claration annuelle \u00e0 cette date et qui sont \u00e9galement soumises aux taxes sur l\u2019affectation des v\u00e9hicules \u00e0 des fins \u00e9conomiques (ex TVS), d\u00e9claration et paiement des taxes<\/p>\n","protected":false},"featured_media":0,"template":"","weblex-importer-activity":[],"weblex-importer-category":[482,5,456],"weblex-importer-tag":[4],"weblex-importer-keyword":[294,299,292,296,295,290,304,291,298,293,302,301,303,310,297],"_links":{"self":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post\/63348"}],"collection":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post"}],"about":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/types\/weblex-importer-post"}],"wp:attachment":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/media?parent=63348"}],"wp:term":[{"taxonomy":"weblex-importer-activity","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-activity?post=63348"},{"taxonomy":"weblex-importer-category","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-category?post=63348"},{"taxonomy":"weblex-importer-tag","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-tag?post=63348"},{"taxonomy":"weblex-importer-keyword","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-keyword?post=63348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}