{"id":61834,"date":"2024-11-30T00:00:00","date_gmt":"2024-11-29T23:00:00","guid":{"rendered":"https:\/\/www.secvergnaud.com\/?post_type=weblex-importer-post&p=61834"},"modified":"2024-11-30T00:00:00","modified_gmt":"2024-11-29T23:00:00","slug":"dividendes-et-interets-de-comptes-courants-dassocies-1669","status":"publish","type":"weblex-importer-post","link":"https:\/\/www.secvergnaud.com\/index.php\/les-infos-du-jour\/dividendes-et-interets-de-comptes-courants-dassocies-1669\/","title":{"rendered":"Dividendes et int\u00e9r\u00eats de comptes courants d\u2019associ\u00e9s"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Date limite de demande de dispense de pr\u00e9l\u00e8vement \u00e0 la source obligatoire non lib\u00e9ratoire pour les revenus \u00e0 percevoir en 2025 \u00e0 formuler aupr\u00e8s de la soci\u00e9t\u00e9 versante<\/p>\n<p>Peuvent b\u00e9n\u00e9ficier de cette dispense :<\/p>\n<ul>\n<li>les personnes dont le revenu fiscal de r\u00e9f\u00e9rence 2023 est inf\u00e9rieur \u00e0 50 000 \u20ac (personne seule) ou 75 000 \u20ac (couples soumis \u00e0 imposition commune) en ce qui concerne le paiement des dividendes<\/li>\n<li>les personnes dont le revenu fiscal de r\u00e9f\u00e9rence 2023 est inf\u00e9rieur \u00e0 25 000 \u20ac (personne seule) ou 50 000 \u20ac (couples soumis \u00e0 imposition commune) en ce qui concerne le paiement des int\u00e9r\u00eats\u2003<br \/>\t&nbsp;<\/li>\n<\/ul>\n","protected":false},"featured_media":0,"template":"","weblex-importer-activity":[],"weblex-importer-category":[482,5,456],"weblex-importer-tag":[4],"weblex-importer-keyword":[294,299,292,300,296,295,290,304,291,298,293,302,301,303,310,297],"_links":{"self":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post\/61834"}],"collection":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post"}],"about":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/types\/weblex-importer-post"}],"wp:attachment":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/media?parent=61834"}],"wp:term":[{"taxonomy":"weblex-importer-activity","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-activity?post=61834"},{"taxonomy":"weblex-importer-category","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-category?post=61834"},{"taxonomy":"weblex-importer-tag","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-tag?post=61834"},{"taxonomy":"weblex-importer-keyword","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-keyword?post=61834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}