{"id":431,"date":"2020-04-28T05:45:00","date_gmt":"2020-04-28T03:45:00","guid":{"rendered":"http:\/\/www.secvergnaud.com\/index.php\/les-infos-du-jour\/taux-de-limpot-sur-les-societes-et-de-la-contribution-additionnelle-annee-2020\/"},"modified":"2020-04-28T05:45:00","modified_gmt":"2020-04-28T03:45:00","slug":"taux-de-limpot-sur-les-societes-et-de-la-contribution-additionnelle-annee-2020","status":"publish","type":"weblex-importer-post","link":"https:\/\/www.secvergnaud.com\/index.php\/les-infos-du-jour\/taux-de-limpot-sur-les-societes-et-de-la-contribution-additionnelle-annee-2020\/","title":{"rendered":"Taux de l\u2019imp\u00f4t sur les soci\u00e9t\u00e9s et de la contribution additionnelle &#8211; Ann\u00e9e 2020"},"content":{"rendered":"<div>\n<p><span style=\"text-decoration: underline\">Taux de l&rsquo;imp\u00f4t sur les soci\u00e9t\u00e9s<\/span><br \/>\u00a0<\/p>\n<p><strong>\u00a0 \u2022 \u00a0 \u00a0 Taux de droit commun<\/strong><\/p>\n<p>Pour les entreprises dont le chiffre d\u2019affaires est inf\u00e9rieur \u00e0 7,63 M\u20ac<\/p>\n<div align=\"center\">\n<div align=\"center\">\n<div align=\"center\">\n<table style=\"width: 501px\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"174\">\n<p><strong>B\u00e9n\u00e9fices imposables<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"71\">\n<p><strong>Exercice 2019<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"77\">\n<p><strong>Exercice 2020<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p><strong>Exercice 2021<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"104\">\n<p><strong>Exercice 2022<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"174\">\n<p>0 \u00e0 38\u00a0120 \u20ac<\/p>\n<\/td>\n<td valign=\"top\" width=\"71\">\n<p>15 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"77\">\n<p>15 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p>15 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"104\">\n<p>15 %<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"174\">\n<p>38\u00a0120 \u20ac \u00e0 500\u00a0000 \u20ac<\/p>\n<\/td>\n<td valign=\"top\" width=\"71\">\n<p>28 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"77\">\n<p>28 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p>26,5 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"104\">\n<p>25 %<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"174\">\n<p>&gt; 500\u00a0000 \u20ac<\/p>\n<\/td>\n<td valign=\"top\" width=\"71\">\n<p>31 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"77\">\n<p>28 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p>26,5 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"104\">\n<p>25 %<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p>\u00a0<\/p><\/div>\n<\/div>\n<p>Pour les entreprises dont le chiffre d\u2019affaires est compris entre 7,63 M\u20ac et 250 M\u20ac<\/p>\n<div align=\"center\">\u00a0<\/div>\n<div align=\"center\">\n<table style=\"width: 510px\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"170\">\n<p><strong>B\u00e9n\u00e9fices imposables<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p><strong>Exercice 2019<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p><strong>Exercice 2020<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p><strong>Exercice 2021<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p><strong>Exercice 2022<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"170\">\n<p>0 \u00e0 500 000 \u20ac<\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p>28%<\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p>28 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p>26,5 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p>25 %<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"170\">\n<p>&gt; 500\u00a0000 \u20ac<\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p>31 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p>28 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p>26,5 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p>25 %<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p><\/p>\n<p>Pour les entreprises dont le chiffre d\u2019affaires est sup\u00e9rieur ou \u00e9gal \u00e0 250 M\u20ac<\/p>\n<div align=\"center\">\n<div align=\"center\">\n<table style=\"width: 508px\" border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td valign=\"top\" width=\"158\">\n<p><strong>B\u00e9n\u00e9fices imposables<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p><strong>Exercice 2019<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p><strong>Exercice 2020<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"85\">\n<p><strong>Exercice 2021<\/strong><\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p><strong>Exercice 2022<\/strong><\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"158\">\n<p>0 \u00e0 500\u00a0000 \u20ac<\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p>28 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p>28 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"85\">\n<p>27,5 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p>25 %<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"158\">\n<p>&gt; 500\u00a0000 \u20ac<\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p>33,1\/3 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"76\">\n<p>31 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"85\">\n<p>27,5 %<\/p>\n<\/td>\n<td valign=\"top\" width=\"113\">\n<p>25 %<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<p><\/p>\n<p><strong>\u00a0 \u2022 \u00a0 \u00a0 Taux r\u00e9duit sur les plus-values \u00e0 long terme<\/strong><\/p>\n<ul>\n<li>19 % pour les titres de participation dans des soci\u00e9t\u00e9s \u00e0 pr\u00e9pond\u00e9rance immobili\u00e8re cot\u00e9es d\u00e9tenus depuis au moins 2 ans<\/li>\n<li>10 % (depuis le 1er janvier 2019) pour les produits nets tir\u00e9s de la sous-concession ou de la concession de licences d&rsquo;exploitation de brevets, d&rsquo;inventions brevetables, de proc\u00e9d\u00e9s de fabrication et de perfectionnements, si l\u2019option pour le nouveau r\u00e9gime d\u2019imposition des brevets est formul\u00e9e. A d\u00e9faut d\u2019option, le taux d\u2019imposition est fix\u00e9 \u00e0 15 %.<\/li>\n<li>15 % pour les plus-values de cession de parts de fonds commun de placement \u00e0 risques et d&rsquo;actions de soci\u00e9t\u00e9s de capital-risque<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline\">Taux de la contribution additionnelle<\/span><\/p>\n<ul>\n<li>Contribution sociale de 3,3 % sur la part de l&rsquo;imp\u00f4t sur les soci\u00e9t\u00e9s qui exc\u00e8de 763 000 \u20ac<\/li>\n<\/ul>\n<p><\/p>\n<p><span style=\"text-decoration: underline\"><strong>Sources :<\/strong><\/span><\/p>\n<ul>\n<li>Article 219 du Code G\u00e9n\u00e9ral des Imp\u00f4ts (taux de l\u2019imp\u00f4t sur les soci\u00e9t\u00e9s)<\/li>\n<li>Article 235 ter ZC du Code G\u00e9n\u00e9ral des Imp\u00f4ts (contribution sociale de 3,3 %)<\/li>\n<li>Loi n\u00b02017-1640 du 1er d\u00e9cembre 2017 de finances rectificative pour 2017<\/li>\n<li>Loi n\u00b02018-1317 du 28 d\u00e9cembre 2018 de finances pour 2019<\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Taux de l&rsquo;imp\u00f4t sur les soci\u00e9t\u00e9s\u00a0 \u00a0 \u2022 \u00a0 \u00a0 Taux de droit commun Pour les entreprises dont le chiffre d\u2019affaires est inf\u00e9rieur \u00e0 7,63 M\u20ac B\u00e9n\u00e9fices imposables Exercice 2019 Exercice 2020 Exercice 2021 Exercice 2022 0 \u00e0 38\u00a0120 \u20ac 15 % 15 % 15 % 15 % 38\u00a0120 \u20ac \u00e0 500\u00a0000 \u20ac 28 % [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","weblex-importer-activity":[],"weblex-importer-category":[44,39],"weblex-importer-tag":[38],"weblex-importer-keyword":[],"_links":{"self":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post\/431"}],"collection":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post"}],"about":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/types\/weblex-importer-post"}],"wp:attachment":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/media?parent=431"}],"wp:term":[{"taxonomy":"weblex-importer-activity","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-activity?post=431"},{"taxonomy":"weblex-importer-category","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-category?post=431"},{"taxonomy":"weblex-importer-tag","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-tag?post=431"},{"taxonomy":"weblex-importer-keyword","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-keyword?post=431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}