{"id":109125,"date":"2025-10-15T00:00:00","date_gmt":"2025-10-14T22:00:00","guid":{"rendered":"https:\/\/www.secvergnaud.com\/?post_type=weblex-importer-post&p=109125"},"modified":"2025-10-15T00:00:00","modified_gmt":"2025-10-14T22:00:00","slug":"retenue-a-la-source-pour-les-non-residents-2493","status":"publish","type":"weblex-importer-post","link":"https:\/\/www.secvergnaud.com\/index.php\/les-infos-du-jour\/retenue-a-la-source-pour-les-non-residents-2493\/","title":{"rendered":"Retenue \u00e0 la source pour les non-r\u00e9sidents"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Date limite de d\u00e9p\u00f4t de la d\u00e9claration et du paiement de la retenue \u00e0 la source applicable aux revenus mobiliers vers\u00e9s \u00e0 des non-r\u00e9sidents en septembre 2025<\/p>\n<p>Date limite de d\u00e9p\u00f4t de la d\u00e9claration et du paiement de la retenue \u00e0 la source applicable :<\/p>\n<ul>\n<li>aux salaires et pensions vers\u00e9s \u00e0 des non-r\u00e9sidents au cours du 3e trimestre 2025<\/li>\n<li>aux revenus non salariaux (honoraires, redevances, etc.) vers\u00e9s \u00e0 des non-r\u00e9sidents au cours du 3e trimestre 2025<\/li>\n<\/ul>\n","protected":false},"featured_media":0,"template":"","weblex-importer-activity":[],"weblex-importer-category":[636,5,625],"weblex-importer-tag":[4],"weblex-importer-keyword":[294,299,292,300,296,295,290,304,291,298,293,302,301,303,310,297],"_links":{"self":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post\/109125"}],"collection":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post"}],"about":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/types\/weblex-importer-post"}],"wp:attachment":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/media?parent=109125"}],"wp:term":[{"taxonomy":"weblex-importer-activity","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-activity?post=109125"},{"taxonomy":"weblex-importer-category","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-category?post=109125"},{"taxonomy":"weblex-importer-tag","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-tag?post=109125"},{"taxonomy":"weblex-importer-keyword","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-keyword?post=109125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}