{"id":108258,"date":"2025-10-15T00:00:00","date_gmt":"2025-10-14T22:00:00","guid":{"rendered":"https:\/\/www.secvergnaud.com\/?post_type=weblex-importer-post&p=108258"},"modified":"2025-10-15T00:00:00","modified_gmt":"2025-10-14T22:00:00","slug":"cotisations-sociales-prelevement-a-la-source-pour-les-salaries-et-assimiles-effectif-de-10-salaries-au-plus-2377","status":"publish","type":"weblex-importer-post","link":"https:\/\/www.secvergnaud.com\/index.php\/les-infos-du-jour\/cotisations-sociales-prelevement-a-la-source-pour-les-salaries-et-assimiles-effectif-de-10-salaries-au-plus-2377\/","title":{"rendered":"Cotisations sociales + Pr\u00e9l\u00e8vement \u00e0 la source pour les salari\u00e9s et assimil\u00e9s (effectif de 10 salari\u00e9s au plus)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Transmission de la DSN pour les salaires de septembre 2025<\/p>\n<p>Collecte et d\u00e9claration du pr\u00e9l\u00e8vement \u00e0 la source (PAS) sur les salaires de septembre 2025<\/p>\n<p>Pour les employeurs payant mensuellement les cotisations, date limite de paiement des cotisations dues pour les salaires de septembre 2025 (cotisations de s\u00e9curit\u00e9 sociale, cotisations d\u2019assurance ch\u00f4mage, versement FNAL, contribution solidarit\u00e9-autonomie, CSG, CRDS)<\/p>\n<p>Pour les employeurs ayant opt\u00e9 pour le paiement trimestriel des cotisations, date limite de paiement des cotisations dues pour les salaires vers\u00e9s au 3\u00e8me trimestre 2025 au titre des salaires de juillet, ao\u00fbt et septembre 2025 (cotisations de s\u00e9curit\u00e9 sociale, cotisations d\u2019assurance ch\u00f4mage, versement FNAL, contribution solidarit\u00e9-autonomie, CSG, CRDS)<\/p>\n<p>Pour les entreprises de moins de 50 salari\u00e9s, d\u00e9claration en DSN et paiement \u00e0 l\u2019URSSAF de la fraction principale de la taxe d\u2019apprentissage et la contribution 1% CPF-CDD dues au titre de septembre 2025<\/p>\n","protected":false},"featured_media":0,"template":"","weblex-importer-activity":[],"weblex-importer-category":[636,5,625],"weblex-importer-tag":[4],"weblex-importer-keyword":[294,299,292,300,296,295,290,291,298,293,302,301,303,310,297],"_links":{"self":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post\/108258"}],"collection":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post"}],"about":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/types\/weblex-importer-post"}],"wp:attachment":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/media?parent=108258"}],"wp:term":[{"taxonomy":"weblex-importer-activity","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-activity?post=108258"},{"taxonomy":"weblex-importer-category","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-category?post=108258"},{"taxonomy":"weblex-importer-tag","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-tag?post=108258"},{"taxonomy":"weblex-importer-keyword","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-keyword?post=108258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}