{"id":107078,"date":"2025-12-19T00:00:00","date_gmt":"2025-12-18T23:00:00","guid":{"rendered":"https:\/\/www.secvergnaud.com\/?post_type=weblex-importer-post&p=107078"},"modified":"2025-12-19T00:00:00","modified_gmt":"2025-12-18T23:00:00","slug":"tva-40801","status":"publish","type":"weblex-importer-post","link":"https:\/\/www.secvergnaud.com\/index.php\/les-infos-du-jour\/tva-40801\/","title":{"rendered":"TVA"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Pour les soci\u00e9t\u00e9s, hors soci\u00e9t\u00e9s anonymes (d\u00e9partements 75, 92, 93, 94), dont les 2 premiers chiffres du code INSEE va de 00 \u00e0 68, d\u00e9p\u00f4t de la d\u00e9claration CA3 et paiement de la TVA au titre des op\u00e9rations r\u00e9alis\u00e9es au titre du mois de novembre 2025, pour les redevables de la TVA selon une p\u00e9riodicit\u00e9 mensuelle (ou au titre du dernier trimestre \u00e9coul\u00e9 pour les redevables de la TVA selon une p\u00e9riodicit\u00e9 trimestrielle le cas \u00e9ch\u00e9ant)<\/p>\n","protected":false},"featured_media":0,"template":"","weblex-importer-activity":[],"weblex-importer-category":[605,5,598],"weblex-importer-tag":[4],"weblex-importer-keyword":[294,299,292,296,295,290,304,291,298,293,302,301,303,310,297],"_links":{"self":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post\/107078"}],"collection":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post"}],"about":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/types\/weblex-importer-post"}],"wp:attachment":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/media?parent=107078"}],"wp:term":[{"taxonomy":"weblex-importer-activity","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-activity?post=107078"},{"taxonomy":"weblex-importer-category","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-category?post=107078"},{"taxonomy":"weblex-importer-tag","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-tag?post=107078"},{"taxonomy":"weblex-importer-keyword","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-keyword?post=107078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}