{"id":107026,"date":"2025-10-15T00:00:00","date_gmt":"2025-10-14T22:00:00","guid":{"rendered":"https:\/\/www.secvergnaud.com\/?post_type=weblex-importer-post&p=107026"},"modified":"2025-10-15T00:00:00","modified_gmt":"2025-10-14T22:00:00","slug":"taxe-sur-les-salaires-2499","status":"publish","type":"weblex-importer-post","link":"https:\/\/www.secvergnaud.com\/index.php\/les-infos-du-jour\/taxe-sur-les-salaires-2499\/","title":{"rendered":"Taxe sur les salaires"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Date limite de paiement et de d\u00e9p\u00f4t du relev\u00e9 de versement provisionnel de la taxe sur les salaires relative aux r\u00e9mun\u00e9rations pay\u00e9es en septembre 2025 (pour les redevables mensuels)<\/p>\n<p>Date limite de paiement et de d\u00e9p\u00f4t du relev\u00e9 de versement provisionnel de la taxe sur les salaires relative aux r\u00e9mun\u00e9rations pay\u00e9es au cours du 3\u00e8me trimestre 2025 (pour les redevables trimestriels)<\/p>\n","protected":false},"featured_media":0,"template":"","weblex-importer-activity":[],"weblex-importer-category":[636,5,625],"weblex-importer-tag":[4],"weblex-importer-keyword":[294,299,292,300,296,295,290,291,298,293,302,301,303,310,297],"_links":{"self":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post\/107026"}],"collection":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post"}],"about":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/types\/weblex-importer-post"}],"wp:attachment":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/media?parent=107026"}],"wp:term":[{"taxonomy":"weblex-importer-activity","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-activity?post=107026"},{"taxonomy":"weblex-importer-category","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-category?post=107026"},{"taxonomy":"weblex-importer-tag","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-tag?post=107026"},{"taxonomy":"weblex-importer-keyword","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-keyword?post=107026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}