{"id":107025,"date":"2025-10-15T00:00:00","date_gmt":"2025-10-14T22:00:00","guid":{"rendered":"https:\/\/www.secvergnaud.com\/?post_type=weblex-importer-post&p=107025"},"modified":"2025-10-15T00:00:00","modified_gmt":"2025-10-14T22:00:00","slug":"dividendes-et-interets-de-comptes-courants-dassocies-3079","status":"publish","type":"weblex-importer-post","link":"https:\/\/www.secvergnaud.com\/index.php\/les-infos-du-jour\/dividendes-et-interets-de-comptes-courants-dassocies-3079\/","title":{"rendered":"Dividendes et int\u00e9r\u00eats de comptes courants d\u2019associ\u00e9s"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Date limite de d\u00e9p\u00f4t de la d\u00e9claration de revenus de capitaux mobiliers, pr\u00e9l\u00e8vement forfaitaire non lib\u00e9ratoire et pr\u00e9l\u00e8vements sociaux dus \u00e0 la source en cas de paiement de revenus distribu\u00e9s et\/ou d\u2019int\u00e9r\u00eats de comptes courants d\u2019associ\u00e9s au cours du mois de septembre 2025<\/p>\n","protected":false},"featured_media":0,"template":"","weblex-importer-activity":[],"weblex-importer-category":[636,5,625],"weblex-importer-tag":[4],"weblex-importer-keyword":[294,299,292,300,296,295,290,304,291,298,293,302,301,303,310,297],"_links":{"self":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post\/107025"}],"collection":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post"}],"about":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/types\/weblex-importer-post"}],"wp:attachment":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/media?parent=107025"}],"wp:term":[{"taxonomy":"weblex-importer-activity","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-activity?post=107025"},{"taxonomy":"weblex-importer-category","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-category?post=107025"},{"taxonomy":"weblex-importer-tag","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-tag?post=107025"},{"taxonomy":"weblex-importer-keyword","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-keyword?post=107025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}