{"id":106796,"date":"2025-10-15T00:00:00","date_gmt":"2025-10-14T22:00:00","guid":{"rendered":"https:\/\/www.secvergnaud.com\/?post_type=weblex-importer-post&p=106796"},"modified":"2025-10-15T00:00:00","modified_gmt":"2025-10-14T22:00:00","slug":"cotisations-sociales-prelevement-a-la-source-pour-les-salaries-et-assimiles-effectif-dau-moins-50-salaries-3576","status":"publish","type":"weblex-importer-post","link":"https:\/\/www.secvergnaud.com\/index.php\/les-infos-du-jour\/cotisations-sociales-prelevement-a-la-source-pour-les-salaries-et-assimiles-effectif-dau-moins-50-salaries-3576\/","title":{"rendered":"Cotisations sociales + Pr\u00e9l\u00e8vement \u00e0 la source pour les salari\u00e9s et assimil\u00e9s (effectif d\u2019au moins 50 salari\u00e9s)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Transmission de la DSN pour les salaires de septembre 2025 vers\u00e9s en octobre 2025<\/p>\n<p>Collecte et d\u00e9claration du pr\u00e9l\u00e8vement \u00e0 la source (PAS) sur les salaires de septembre 2025 vers\u00e9s en octobre 2025<\/p>\n<p>Date limite de paiement de cotisations dues pour les salaires de septembre 2025 vers\u00e9s en octobre 2025 (cotisations de s\u00e9curit\u00e9 sociale, cotisations d\u2019assurance ch\u00f4mage, versement transport, versement FNAL, contribution solidarit\u00e9-autonomie, CSG, CRDS)<\/p>\n<p>Pour les entreprises de plus de 50 salari\u00e9s pratiquant le d\u00e9calage de paye d\u00e9claration en DSN et paiement \u00e0 l\u2019URSSAF de la contribution \u00e0 la formation professionnelle et \u00e0 la contribution 1% CPF-CDD dues au titre de septembre 2025<\/p>\n","protected":false},"featured_media":0,"template":"","weblex-importer-activity":[],"weblex-importer-category":[636,5,625],"weblex-importer-tag":[4],"weblex-importer-keyword":[294,299,292,300,296,295,290,291,298,293,302,301,303,310,297],"_links":{"self":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post\/106796"}],"collection":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-post"}],"about":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/types\/weblex-importer-post"}],"wp:attachment":[{"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/media?parent=106796"}],"wp:term":[{"taxonomy":"weblex-importer-activity","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-activity?post=106796"},{"taxonomy":"weblex-importer-category","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-category?post=106796"},{"taxonomy":"weblex-importer-tag","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-tag?post=106796"},{"taxonomy":"weblex-importer-keyword","embeddable":true,"href":"https:\/\/www.secvergnaud.com\/index.php\/wp-json\/wp\/v2\/weblex-importer-keyword?post=106796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}